{"id":235156,"date":"2025-04-14T14:31:09","date_gmt":"2025-04-14T20:31:09","guid":{"rendered":"https:\/\/www.coloradolegalservices.org\/?post_type=tribe_events&#038;p=235156"},"modified":"2025-04-14T14:35:30","modified_gmt":"2025-04-14T20:35:30","slug":"ley-de-parques-de-casas-moviles","status":"publish","type":"tribe_events","link":"https:\/\/www.coloradolegalservices.org\/es\/event\/virtual-senior-law-series-mobile-home-park-act\/","title":{"rendered":"Serie de leyes virtuales para mayores: Ley de parques de casas m\u00f3viles"},"content":{"rendered":"<p>Organizaciones de asistencia jur\u00eddica y bufetes de abogados est\u00e1n organizando una serie virtual de derecho de la tercera edad en la vertiente occidental. El evento del 2 de mayo cubrir\u00e1 la Ley de Parques de Casas M\u00f3viles.<\/p>\n<a href=\"https:\/\/www.eventbrite.com\/e\/virtual-senior-law-series-spring-2025-tickets-1110758451429?aff=oddtdtcreator\" class=\"small-button smallblue\" target=\"_blank\" rel=\"noopener\">INSCR\u00cdBETE AQU\u00cd<\/a>","protected":false},"excerpt":{"rendered":"<p>Organizaciones de asistencia jur\u00eddica y bufetes de abogados est\u00e1n organizando una serie virtual de derecho de la tercera edad en la vertiente occidental. El evento del 2 de mayo cubrir\u00e1 la Ley de Parques de Casas M\u00f3viles.<\/p>","protected":false},"author":5,"featured_media":235155,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-235156","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.coloradolegalservices.org\/es\/wp-json\/wp\/v2\/tribe_events\/235156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coloradolegalservices.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.coloradolegalservices.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.coloradolegalservices.org\/es\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":0,"href":"https:\/\/www.coloradolegalservices.org\/es\/wp-json\/wp\/v2\/tribe_events\/235156\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coloradolegalservices.org\/es\/wp-json\/wp\/v2\/media\/235155"}],"wp:attachment":[{"href":"https:\/\/www.coloradolegalservices.org\/es\/wp-json\/wp\/v2\/media?parent=235156"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.coloradolegalservices.org\/es\/wp-json\/wp\/v2\/tags?post=235156"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.coloradolegalservices.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=235156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}